{"id":10645,"date":"2021-04-01T12:41:15","date_gmt":"2021-04-01T10:41:15","guid":{"rendered":"https:\/\/ritme.com\/software\/sigmaplot\/"},"modified":"2026-04-02T09:35:19","modified_gmt":"2026-04-02T07:35:19","slug":"sigmaplot","status":"publish","type":"software","link":"https:\/\/ritme.com\/it\/software\/sigmaplot\/","title":{"rendered":"SigmaPlot"},"content":{"rendered":"\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-tablet uagb-columns__valign- uagb-columns__gap-10 align uagb-block-8476d78c uagb-columns__columns-2 uagb-columns__max_width-theme video-text-columns valign-center\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-00161a8f\"><div class=\"uagb-column__overlay\"><\/div>\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-097909e2 section-video\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<figure class=\"wp-block-image size-full is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"676\" height=\"456\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-page-logiciel-2.png\" alt=\"\" class=\"wp-image-53797\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-page-logiciel-2.png 676w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-page-logiciel-2-500x337.png 500w\" sizes=\"auto, (max-width: 676px) 100vw, 676px\" \/><\/figure>\n<\/div><\/section>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-3d4a513a\"><div class=\"uagb-column__overlay\"><\/div>\n<h2 class=\"wp-block-heading\">SigmaPlot 16, il software per l&#8217;analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SigmaPlot \u00e8 un potente software di analisi e visualizzazione dei dati scientifici che consente di creare e personalizzare rapidamente grafici tecnici in 2D e 3D. Completo di un modulo statistico per esperti, dispone anche di un modulo per l&#8217;analisi della cinetica enzimatica.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Riferimento storico della comunit\u00e0 scientifica, questo strumento \u00e8 utilizzato in tutto il mondo.<\/strong><\/p>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-tablet uagb-columns__valign- uagb-columns__gap-10 align uagb-block-88c89b43 uagb-columns__columns-2 uagb-columns__max_width-theme reasons-and-testimonial\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-c7340fe4 reasons-list\"><div class=\"uagb-column__overlay\"><\/div>\n<h2 class=\"wp-block-heading\"><strong>5<\/strong> buoni motivi per utilizzare questo prodotto<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Analizzare i dati con facilit\u00e0<\/li>\n\n\n\n<li>Accesso a oltre 100 tipi di grafica 2D e 3D<\/li>\n\n\n\n<li>Personalizzare ogni dettaglio di tabelle e grafici<\/li>\n\n\n\n<li>Pubblicate la vostra grafica dove volete<\/li>\n\n\n\n<li>Utilizzate SigmaPlot direttamente da Microsoft Excel<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-f3df9dc8\"><div class=\"uagb-column__overlay\"><\/div><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-none uagb-columns__stack-tablet uagb-columns__valign- uagb-columns__gap-10 align uagb-block-4d8d2092 uagb-columns__columns-2 uagb-columns__max_width-theme content-with-right-sidebar\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-c5306645 main-col\"><div class=\"uagb-column__overlay\"><\/div>\n\tThis form cannot be loaded from admin screens\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-78d581cb section-intro-text\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h3 class=\"wp-block-heading\" id=\"pourquoi\"><mark style=\"padding:0px;background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ritme-blue-color\">Perch\u00e9 scegliere SigmaPlot?<\/mark><\/h3>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SigmaPlot <\/strong>incorpora funzioni per soddisfare le diverse esigenze dei ricercatori, sia per l&#8217;analisi che per la rappresentazione dei dati. Questo strumento offre la flessibilit\u00e0 necessaria per creare grafici avvincenti e analisi statistiche avanzate che non si possono fare con un foglio di calcolo di base.<\/p>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"215\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/logiciel-sigmaplot-screenshots.jpeg\" alt=\"\" class=\"wp-image-3461\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/logiciel-sigmaplot-screenshots.jpeg 550w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/logiciel-sigmaplot-screenshots-500x195.jpeg 500w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">La scelta di un&#8217;ampia gamma di figure<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">SigmaPlot offre <strong>oltre 100 tipi di figure 2D e 3D<\/strong>. Dalle semplici nuvole di punti 2D alle complesse curve di livello, Sigmaplot offre tutte le rappresentazioni grafiche necessarie per il vostro lavoro di ricerca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Osservate in SigmaPlot le <strong>interazioni nei vostri dati 3D <\/strong>con pi\u00f9 maglie trasversali 3D e la rimozione delle linee nascoste.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Analisi dei dati semplificata<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Dalle statistiche di base ai calcoli matematici avanzati, SigmaPlot vi offre tutti gli strumenti necessari per analizzare i vostri dati. Con un semplice clic, \u00e8 possibile generare istantaneamente statistiche sui risultati, compresi gli <strong>intervalli di confidenza <\/strong>del 95% e del 99%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questi strumenti consentono di eseguire facilmente un test t o una regressione lineare, analizzare <strong>una curva ROC<\/strong>, adattare le curve, tracciare una funzione e riportare i risultati in pochi secondi. Utilizzate anche le trasformazioni integrate per lavorare con i dati e creare grafici unici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, SigmaPlot include un modulo di <strong>cinetica enzimatica<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Dati regolati in modo semplice e preciso<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Per aiutarvi a regolare i dati, SigmaPlot <strong>dispone di una procedura guidata di regressione<\/strong><strong>. <\/strong>Imposta automaticamente i parametri, scrive un rapporto statistico completo, salva l&#8217;equazione e presenta i risultati in un grafico esistente o nuovo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Regressione guidata si adatta a quasi tutti i tipi di equazioni (continua, multifunzionale, ponderata, booleana, ecc.) fino a 10 variabili e 25 parametri. \u00c8 anche possibile aggiungere le proprie equazioni di adattamento alla Regressione guidata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con Sigmaplot \u00e8 possibile anche analizzare gli effetti della dose e calcolare la dose EC50.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Software compatibile con Microsoft Excel<sup>\u00ae<\/sup><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Accedete a SigmaPlot direttamente dal vostro <strong>foglio di calcolo Excel <\/strong>per analizzare e valutare i vostri dati. \u00c8 sufficiente lanciare la <strong>procedura guidata SigmaPlot <\/strong>dalla barra degli strumenti di Excel. Viceversa, tutti gli strumenti di Excel sono disponibili in SigmaPlot: funzioni, tabelle pivot, macro, formati di data, ecc. Potete analizzare i dati della vostra tabella Excel direttamente in SigmaPlot e generare grafici avanzati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SigmaPlot \u00e8 certificato FDA e conforme alla normativa <a href=\"https:\/\/www.fda.gov\/regulatory-information\/search-fda-guidance-documents\/part-11-electronic-records-electronic-signatures-scope-and-application\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"padding:0px;background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ritme-blue-color\">CFR21 Part 11 Regressione<\/mark><\/a>.<\/p>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:20px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"377\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/logiciel-sigmaplot-representation-3D.png\" alt=\"\" class=\"wp-image-3453\"\/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:51px\" aria-hidden=\"true\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"features\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ritme-blue-color\">Cosa c&#8217;\u00e8 di nuovo in SigmaPlot v16<\/mark><\/h3>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Un nuovo tipo di grafico: la mappa di calore<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Visualizzare le variazioni di densit\u00e0 di due variabili categoriali. Questa mappa, sotto forma di tabella rettangolare di colori solidi, pu\u00f2 essere visualizzata in una tabella in cui le righe si riferiscono ai livelli di una variabile e le colonne a un&#8217;altra. &nbsp;<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"429\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/carte-chaleur.jpg\" alt=\"Carte de chaleur - SigmaPlot v15\" class=\"wp-image-29772\" style=\"width:492px;height:322px\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/carte-chaleur.jpg 656w, https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/carte-chaleur-500x327.jpg 500w\" sizes=\"auto, (max-width: 656px) 100vw, 656px\" \/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Modifiche all&#8217;interfaccia per migliorare l&#8217;esperienza dell&#8217;utente<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><strong>Nuovo gestore di nastri<\/strong><\/strong>: per una migliore esperienza utente e una navigazione semplificata con nastri che raggruppano le funzionalit\u00e0 in base al contesto.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"361\" height=\"124\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/gestionnaire-ruban.jpg\" alt=\"Gestionnaire de ruban\" class=\"wp-image-29776\"\/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nuovo pulsante home<\/strong>: rende molto facile trovare le funzionalit\u00e0 di base come l&#8217;avvio rapido, la creazione di nuovi quaderni, l&#8217;apertura di un file esistente, la protezione della cartella di lavoro con password&#8230;<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"154\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/bouton-accueil.jpg\" alt=\"Nouveau bouton d'accueil\" class=\"wp-image-29780\" style=\"width:167px;height:116px\"\/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nuova scheda Macro<\/strong>: SigmaPlot v16 presenta ora una scheda Macro separata per facilitare la navigazione e consentire agli utenti di creare rapidamente le proprie macro. Lo strumento dispone di trenta macro integrate.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"81\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/Onglet-Macros.jpg\" alt=\"Nouvel onglet Macros\" class=\"wp-image-29784\"\/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nuovo gruppo Istogrammi nella scheda Analisi<\/strong>: questa scheda \u00e8 stata riorganizzata per includere un nuovo gruppo Istogrammi per facilitare la creazione e l&#8217;impostazione avanzata di questo tipo di grafico.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"695\" height=\"111\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/Histogrammes-Analyse.jpg\" alt=\"Nouveau groupe Histogrammes dans l'onglet Analyse\" class=\"wp-image-29788\" style=\"width:521px;height:83px\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/Histogrammes-Analyse.jpg 695w, https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/Histogrammes-Analyse-500x80.jpg 500w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nuova scheda Strumenti<\/strong>: fornisce un accesso semplificato alle macro e alle applicazioni che si interfacciano con le funzionalit\u00e0 di SigmaPlot, per approfondire le capacit\u00e0 del programma.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"111\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/onglet-Outils.jpg\" alt=\"Nouvel onglet Outils\" class=\"wp-image-29792\" style=\"width:523px;height:83px\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/onglet-Outils.jpg 697w, https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/onglet-Outils-500x80.jpg 500w\" sizes=\"auto, (max-width: 697px) 100vw, 697px\" \/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Caratteristiche dell&#8217;analisi<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Grafici dei risultati<\/strong>: ora \u00e8 possibile salvare i dati dei grafici dei risultati, con rapporti statistici.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"418\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/Graphiques-resultats.jpg\" alt=\"Graphiques de r\u00e9sultats\" class=\"wp-image-29796\" style=\"width:221px;height:314px\"\/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Finestra di dialogo Trasformazione definita dall&#8217;utente<\/strong>: una nuova casella di controllo consente alla finestra di dialogo di continuare a essere eseguita dopo aver premuto il pulsante Esegui. Utile per verificare i risultati di una trasformazione.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"465\" height=\"391\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2022\/11\/boite-dialogue.jpg\" alt=\"Bo\u00eete de dialogue Transformation d\u00e9finie par l\u2019utilisateur\" class=\"wp-image-29800\" style=\"width:349px;height:293px\"\/><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Nuovo sistema di licenze<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nuovo sistema di attivazione basato su cloud, disponibile 24 ore su 24, 7 giorni su 7, per una migliore attivazione.<\/li>\n\n\n\n<li>Il server delle licenze di rete \u00e8 stato aggiornato all&#8217;ultima versione di Sentinel License Manager, compatibile con l&#8217;ultima versione di Microsoft Server 2022.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:50px\" aria-hidden=\"true\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"Configuration\"><mark style=\"padding:0px;background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-ritme-blue-color\">Requisiti di sistema<\/mark><\/h3>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:15px\" aria-hidden=\"true\"><\/div>\n\n\n\n<div class=\"wp-block-getwid-table\"><table><tbody><tr><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;background-color:#D7E4EF;color:#373f41;border-color:#ffffff;border-width:3px\">Sistema operativo<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;background-color:#D7E4EF;color:#373f41;border-color:#ffffff;border-width:3px\">Versione<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;background-color:#D7E4EF;color:#373f41;border-color:#ffffff;border-width:3px\">Processore<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;background-color:#D7E4EF;color:#373f41;border-color:#ffffff;border-width:3px\">Memoria<br>ad accesso casuale (RAM)<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;background-color:#D7E4EF;color:#373f41;border-color:#ffffff;border-width:3px\">Disco rigido<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;background-color:#D7E4EF;color:#373f41;border-color:#ffffff;border-width:3px\">CD-rom \/ DVD-rom<\/td><td style=\"background-color:#D7E4EF;color:#373f41;border-color:#ffffff;border-width:3px;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;text-align:center;vertical-align:middle\">Accesso a Internet<\/td><\/tr><tr><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;background-color:#f1f8fb;border-color:#ffffff;border-width:3px\"><strong>Microsoft Windows<\/strong><\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;border-color:#ffffff;border-width:3px;background-color:#fbfcfd\"> Windows 10 o superiore<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;border-color:#ffffff;border-width:3px;background-color:#fbfcfd\">Intel o AMD<br>32\/64 bits<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;border-color:#ffffff;border-width:3px;background-color:#fbfcfd\">256 MB (minimo)<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;border-color:#ffffff;border-width:3px;background-color:#fbfcfd\">150 MB<\/td><td style=\"text-align:center;vertical-align:middle;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;border-color:#ffffff;border-width:3px;background-color:#fbfcfd\">Si<\/td><td style=\"border-color:#ffffff;border-width:3px;padding-top:5px;padding-right:5px;padding-bottom:5px;padding-left:5px;text-align:center;vertical-align:middle;background-color:#fbfcfd\">Si<\/td><\/tr><\/tbody><\/table><\/div>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:60px\" aria-hidden=\"true\"><\/div>\n<\/div><\/section>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-20bb57fe\"><div class=\"uagb-column__overlay\"><\/div><div class=\"sidebar-submenu wp-block-create-block-sidebar\"><div class=\"backend-only\">Internal links are generated on the front page only.<\/div><\/div>\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-222b8d97 custom-shadow\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\t\t<div id=\"software-prices-block_0d2e7375fd2e5464c353e50406faba2a\" class=\"software-prices not-editable mb-5 card\">\n\t\t\t\t\t\t\t\t<div class=\"starting-from\">A partire da (IVA esclusa)<\/div>\n\t\t\t<div class=\"section-title\">Tariffe<\/div>\n\t\t\t<div class=\"prices-lines\"><div class=\"price-line\"><div class=\"title\">Licenza perpetua<\/div><div class=\"price\">899 \u20ac<\/div><\/div><\/div>\n\t\t\t\t<div class=\"button-wrapper text-center\">\n\t\t\t<div class=\"wp-block-button has-icon icon-euro\"><a href=\"#\" data-bs-toggle=\"modal\" data-bs-target=\"#loginModal\" data-redirect=\"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/software\/10645\/#software-products-form\" class=\"wp-block-button__link open-login-with-redirect\">Accedi per vedere tutti i prezzi<\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/section>\n\n\n\t<div class=\"btn-wrapper mb-3\">\n\t\t<div class=\"wp-block-button large-btn is-next\">\n\t\t\t<a class=\"wp-block-button__link trial-btn\" href=\"https:\/\/ritme.com\/it\/contact\/?subject=trial&#038;message=Voglio+scaricare+una+versione+di+prova+del+software%3A+SigmaPlot&#038;softwareId=10645&#038;_wpnonce=92e523080b\">Scarica la versione di prova<\/a>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\n\n\n\n\t<div class=\"latest-article-wrapper mt-5\">\n\t\t<div class=\"post post-teaser custom-shadow mb-5\">\n\t<div class=\"post-inner card\">\n\t\t<a href=\"https:\/\/ritme.com\/it\/webinar\/sigmaplot-v16-new-and-specialised-graphs\/\" class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"677\" height=\"457\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2026\/03\/img-page-webinaire-SigmaPlot-v16-1.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2026\/03\/img-page-webinaire-SigmaPlot-v16-1.png 677w, https:\/\/ritme.com\/wp-content\/uploads\/2026\/03\/img-page-webinaire-SigmaPlot-v16-1-500x338.png 500w\" sizes=\"auto, (max-width: 677px) 100vw, 677px\" \/><\/a>\n\t\t<div class=\"content\">\n\t\t\t<div class=\"date\">23\/03\/2026<\/div>\n\t\t\t<div class=\"category\"><\/div>\n\t\t\t<h2 class=\"title\"><a href=\"https:\/\/ritme.com\/it\/webinar\/sigmaplot-v16-new-and-specialised-graphs\/\">Webinar SigmaPlot V16 &#8211; New and Specialised Graphs<\/a><\/h2>\n\t\t\t<div class=\"teaser\"><p>webinar in inglese<\/p>\n<\/div>\n\t\t\t<div class=\"wp-block-button is-next more-link text-right\"><a href=\"https:\/\/ritme.com\/it\/webinar\/sigmaplot-v16-new-and-specialised-graphs\/\" class=\"wp-block-button__link\">Leggere di pi\u00f9<\/a><\/div>\n\t\t\t<div class=\"more-link link-text text-right\"><a href=\"https:\/\/ritme.com\/it\/webinar\/sigmaplot-v16-new-and-specialised-graphs\/\">Leggere di pi\u00f9<\/a><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t<\/div>\n\t<\/div>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>SigmaPlot 16, il software per l&#8217;analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri.<\/p>\n","protected":false},"featured_media":53801,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"software-category":[136],"class_list":["post-10645","software","type-software","status-publish","has-post-thumbnail","hentry","software-category-analisi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SigmaPlot - RITME<\/title>\n<meta name=\"description\" content=\"SigmaPlot 16, il software per l&#039;analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ritme.com\/it\/software\/sigmaplot\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SigmaPlot - RITME\" \/>\n<meta property=\"og:description\" content=\"SigmaPlot 16, il software per l&#039;analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ritme.com\/it\/software\/sigmaplot\/\" \/>\n<meta property=\"og:site_name\" content=\"RITME\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-02T07:35:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/software\\\/sigmaplot\\\/\",\"url\":\"https:\\\/\\\/ritme.com\\\/it\\\/software\\\/sigmaplot\\\/\",\"name\":\"SigmaPlot - RITME\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/software\\\/sigmaplot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/software\\\/sigmaplot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/img-mise-en-avant-2.png\",\"datePublished\":\"2021-04-01T10:41:15+00:00\",\"dateModified\":\"2026-04-02T07:35:19+00:00\",\"description\":\"SigmaPlot 16, il software per l'analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/software\\\/sigmaplot\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ritme.com\\\/it\\\/software\\\/sigmaplot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/software\\\/sigmaplot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/img-mise-en-avant-2.png\",\"contentUrl\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/img-mise-en-avant-2.png\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/software\\\/sigmaplot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ritme.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Software\",\"item\":\"https:\\\/\\\/ritme.com\\\/it\\\/software-it\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SigmaPlot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ritme.com\\\/it\\\/\",\"name\":\"RITME\",\"description\":\"Il partner strategico dei team di ricerca\",\"publisher\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ritme.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#organization\",\"name\":\"RITME\",\"url\":\"https:\\\/\\\/ritme.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Logo-Yoast.png\",\"contentUrl\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Logo-Yoast.png\",\"width\":696,\"height\":696,\"caption\":\"RITME\"},\"image\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ritme-scientific-solutions\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ritme6705\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SigmaPlot - RITME","description":"SigmaPlot 16, il software per l'analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ritme.com\/it\/software\/sigmaplot\/","og_locale":"it_IT","og_type":"article","og_title":"SigmaPlot - RITME","og_description":"SigmaPlot 16, il software per l'analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri.","og_url":"https:\/\/ritme.com\/it\/software\/sigmaplot\/","og_site_name":"RITME","article_modified_time":"2026-04-02T07:35:19+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ritme.com\/it\/software\/sigmaplot\/","url":"https:\/\/ritme.com\/it\/software\/sigmaplot\/","name":"SigmaPlot - RITME","isPartOf":{"@id":"https:\/\/ritme.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ritme.com\/it\/software\/sigmaplot\/#primaryimage"},"image":{"@id":"https:\/\/ritme.com\/it\/software\/sigmaplot\/#primaryimage"},"thumbnailUrl":"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png","datePublished":"2021-04-01T10:41:15+00:00","dateModified":"2026-04-02T07:35:19+00:00","description":"SigmaPlot 16, il software per l'analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri.","breadcrumb":{"@id":"https:\/\/ritme.com\/it\/software\/sigmaplot\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ritme.com\/it\/software\/sigmaplot\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ritme.com\/it\/software\/sigmaplot\/#primaryimage","url":"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png","contentUrl":"https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/ritme.com\/it\/software\/sigmaplot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ritme.com\/it\/"},{"@type":"ListItem","position":2,"name":"Software","item":"https:\/\/ritme.com\/it\/software-it\/"},{"@type":"ListItem","position":3,"name":"SigmaPlot"}]},{"@type":"WebSite","@id":"https:\/\/ritme.com\/it\/#website","url":"https:\/\/ritme.com\/it\/","name":"RITME","description":"Il partner strategico dei team di ricerca","publisher":{"@id":"https:\/\/ritme.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ritme.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ritme.com\/it\/#organization","name":"RITME","url":"https:\/\/ritme.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ritme.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ritme.com\/wp-content\/uploads\/2026\/05\/Logo-Yoast.png","contentUrl":"https:\/\/ritme.com\/wp-content\/uploads\/2026\/05\/Logo-Yoast.png","width":696,"height":696,"caption":"RITME"},"image":{"@id":"https:\/\/ritme.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/ritme-scientific-solutions\/","https:\/\/www.youtube.com\/@ritme6705"]}]}},"uagb_featured_image_src":{"full":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png",300,300,false],"thumbnail":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png",300,300,false],"medium":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png",300,300,false],"medium_large":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png",300,300,false],"large":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png",300,300,false],"1536x1536":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png",300,300,false],"2048x2048":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/04\/img-mise-en-avant-2.png",300,300,false]},"uagb_author_info":{"display_name":"Olivier Ritme","author_link":"https:\/\/ritme.com\/it\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"SigmaPlot 16, il software per l'analisi dei dati e la creazione di grafici progettato per ricercatori, scienziati e ingegneri.","_links":{"self":[{"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/software\/10645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/software"}],"about":[{"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/types\/software"}],"version-history":[{"count":17,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/software\/10645\/revisions"}],"predecessor-version":[{"id":53822,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/software\/10645\/revisions\/53822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/media\/53801"}],"wp:attachment":[{"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/media?parent=10645"}],"wp:term":[{"taxonomy":"software-category","embeddable":true,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/software-category?post=10645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}