{"id":2851,"date":"2021-03-18T15:36:42","date_gmt":"2021-03-18T14:36:42","guid":{"rendered":"https:\/\/ritme.com\/publication-et-communication\/"},"modified":"2021-09-28T17:50:32","modified_gmt":"2021-09-28T15:50:32","slug":"pubblicazione-e-comunicazione","status":"publish","type":"page","link":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/","title":{"rendered":"Pubblicazione e comunicazione"},"content":{"rendered":"\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-tablet uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-block-fed8d63f big-image-text-columns valign-center\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-c9112455\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/\/2021\/06\/Publication-et-communication-1.svg\" alt=\"\" class=\"wp-image-11549\" width=\"512\" height=\"452\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-12067887\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<h2 class=\"wp-block-heading\">Pubblicazione e comunicazione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Come culmine della ricerca,&nbsp;<strong>la pubblicazione e la comunicazione<\/strong>&nbsp;sono la vetrina&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ci assicuriamo di offrire soluzioni&nbsp;in linea con le vostre sfide,&nbsp;permettendo&nbsp;<strong>raccogliere,&nbsp;condividere e accedere alle informazioni<\/strong> semplicemente&nbsp;: Soluzioni&nbsp;di&nbsp;gestione delle risorse documentali,&nbsp;strumento di disegno molecolare,&nbsp;ma anche formazione&nbsp;intorno alla scrittura e alla comunicazione scientifica fanno parte dei nostri servizi per accompagnarvi su questi temi. &nbsp;&nbsp;Spesso alla fine del lavoro di ricerca, la pubblicazione e la comunicazione sono la vetrina delle vostra capacit\u00e0.<\/p>\n<\/div><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-tablet uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-block-474c5116 content-with-right-sidebar\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-a261acbd\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-f2c70fb8 section-intro-text\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<p class=\"is-intro wp-block-paragraph\">In un laboratorio o un&#8217;organizzazione che lavora nella R&amp;D, non \u00e8 raro chiedersi come <strong>organizzare al meglio il proprio velo<\/strong>, per&nbsp;<strong>gestire l&#8217;acquisto di documenti<\/strong>&nbsp; e pubblicazioni, per&nbsp;<strong>condividere le&nbsp;risorse documentarie<\/strong>&nbsp;e per realizzare la&nbsp;<strong>scrittura di articoli scientifici<\/strong>, al fine di pubblicarli o diffondere le informazioni ad un vasto pubblico. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per&nbsp;aiutarvi a rispondere a questi problemi con soluzioni tangibili,&nbsp;\u00e8 essenziale esaminare la vostra attivit\u00e0, la vostra struttura e il posto che occupa la&nbsp;<strong>gestione e organizzazione della conoscenza<\/strong>&nbsp;e ci\u00f2 che oggi si chiama <strong>Information Intelligence<\/strong>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"organsiation\"><span class=\"has-inline-color has-ritme-blue-color\">Organizzare il proprio orologio scientifico e condividere le risorse<\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A seconda della vostra struttura, dei vostri vincoli informatici e delle vostre attivit\u00e0, le vostre necessit\u00e0 in termini di vigilanza scientifica e di condivisione delle risorse bibliografiche possono variare.&nbsp;Su quali basi di dati potrete&nbsp;<strong>sorgere<\/strong>&nbsp;i vostri contenuti? Come gestite&nbsp;<strong>i vostri acquisti di pubblicazioni<\/strong>&nbsp;e&nbsp;<strong>i brevetti<\/strong>? Dove vuoi<strong>&nbsp;conservare<\/strong>&nbsp;i vostri dati e come vuoi <strong>condividerli<\/strong>?<\/p>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-mobile uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-block-efd67f80 text-card custom-shadow valign-center\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-532d6fea\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<div class=\"wp-block-getwid-section getwid-margin-bottom-small\" style=\"margin-top:-25px\"><div class=\"wp-block-getwid-section__wrapper getwid-padding-top-none getwid-padding-left-none\" style=\"min-height:0px\"><div class=\"wp-block-getwid-section__inner-wrapper\"><div class=\"wp-block-getwid-section__background-holder\"><div class=\"wp-block-getwid-section__background\"><\/div><div class=\"wp-block-getwid-section__foreground\"><\/div><\/div><div class=\"wp-block-getwid-section__content\"><div class=\"wp-block-getwid-section__inner-content\">\n<div class=\"wp-block-image is-style-default\"><figure class=\"alignleft size-large is-resized\"><a href=\"https:\/\/ritme.com\/it\/software\/citavi\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/citavi-logo.svg\" alt=\"\" class=\"wp-image-16886\" width=\"300\" height=\"107\"\/><\/a><\/figure><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-citavi-enrichissement-base.jpeg\" alt=\"\" class=\"wp-image-2154\" width=\"315\" height=\"197\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-citavi-enrichissement-base.jpeg 933w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-citavi-enrichissement-base-500x313.jpeg 500w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-citavi-enrichissement-base-768x481.jpeg 768w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-getwid-section getwid-margin-top-none getwid-margin-bottom-none\"><div class=\"wp-block-getwid-section__wrapper getwid-padding-bottom-medium getwid-padding-right-none getwid-margin-left-none getwid-margin-right-none\" style=\"padding-left:5px\"><div class=\"wp-block-getwid-section__inner-wrapper\"><div class=\"wp-block-getwid-section__background-holder\"><div class=\"wp-block-getwid-section__background\"><\/div><div class=\"wp-block-getwid-section__foreground\"><\/div><\/div><div class=\"wp-block-getwid-section__content\"><div class=\"wp-block-getwid-section__inner-content\">\n<p class=\"has-text-align-left read-more wp-block-paragraph\"><a href=\"https:\/\/ritme.com\/it\/software\/citavi\/\">Scoprire citavi<\/a> <\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-e4095686\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<p class=\"wp-block-paragraph\"><strong>Citavi<\/strong>, una soluzione innovativa&nbsp;in crescita, offre&nbsp;una condivisione&nbsp;semplice e strutturata&nbsp;di riferimenti, annotazioni e informazioni attraverso l&#8217;archiviazione dei dati&nbsp;in locale,&nbsp;nel cloud o su un server. Questo strumento, che \u00e8 molto pi\u00f9 di uno strumento di riferimento bibliografico&nbsp;e sta per&nbsp;<strong>sostituire soluzioni datate e poco innovative<\/strong>,&nbsp;in questo particolare campo,&nbsp;pu\u00f2 figurare&nbsp;<strong>al centro del vostro pensiero sulla gestione e la condivisione della conoscenza all&#8217;interno della vostra organizzazione.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facciamo molte migrazioni di parchi esistenti dopo aver pensato&nbsp;insieme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assistiamo anche i nostri clienti nell&nbsp;implementazione di strategie&nbsp;di monitoraggio, pubblicazione e outreach. <\/p>\n<\/div><\/div>\n<\/div><\/section>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"achat\"><span class=\"has-inline-color has-ritme-blue-color\">Acquisto di pubblicazioni e brevetti<\/span><\/h3>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-mobile uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-columns__reverse-mobile uagb-block-81889ff9 text-image-columns valign-center\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-7a122853\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<p class=\"wp-block-paragraph\">L&#8217;acquisto centralizzato delle risorse scientifiche e il controllo degli ordini \u00e8 essenziale per garantire una base di conoscenza chiara e solida, evitando sprechi di tempo e denaro. I nostri esperti hanno selezionato per voi <a href=\"https:\/\/ritme.com\/it\/software\/article-galaxy\/\">Article Galaxy<\/a>, la piattaforma di riferimento per l&#8217;acquisto di pubblicazioni scientifiche e brevetti.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-15ecf865\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"alignright size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"873\" height=\"1024\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-article-galaxy-architecture-873x1024.png\" alt=\"\" class=\"wp-image-2732\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-article-galaxy-architecture-873x1024.png 873w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-article-galaxy-architecture-426x500.png 426w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-article-galaxy-architecture-768x901.png 768w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/logiciel-article-galaxy-architecture.png 1088w\" sizes=\"auto, (max-width: 873px) 100vw, 873px\" \/><\/figure><\/div>\n<\/div><\/div>\n<\/div><\/section>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"chimie\"><span class=\"has-inline-color has-ritme-blue-color\">Gestion du contenu chimique &amp; communication<\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al cuore della<strong>&nbsp;comunicazione chimica<\/strong>, il design molecolare \u00e8 molto pi\u00f9 di uno strumento di progettazione. Come la suite&nbsp;<a href=\"https:\/\/ritme.com\/it\/software\/chemdraw-chemoffice\/\">Chemoffice+ Cloud<\/a>, questi strumenti sono dei veri e propri toolkit per le vostre attivit\u00e0 di R&amp;D, e vi permettono di raccogliere, centralizzare e ottimizzare l&#8217;uso delle vostre molecole e reazioni.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Scopri in particolare l&#8217;applicazione&nbsp;<a href=\"https:\/\/ritme.com\/it\/software\/chemdraw-chemoffice\/\">Chemoffice+ Cloud<\/a>, che&nbsp;permette&nbsp;di recuperare in pochi clic tutti i contenuti chimici disponibili sul vostro computer e persi in cartelle multiple,&nbsp;powerpoint,&nbsp;word&nbsp;o altro.&nbsp;<\/p>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-mobile uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-block-886c9665 text-card custom-shadow valign-center\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-83032e36\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<div class=\"wp-block-getwid-section getwid-margin-bottom-small\" style=\"margin-top:-25px\"><div class=\"wp-block-getwid-section__wrapper getwid-padding-top-none getwid-padding-left-none\" style=\"min-height:0px\"><div class=\"wp-block-getwid-section__inner-wrapper\"><div class=\"wp-block-getwid-section__background-holder\"><div class=\"wp-block-getwid-section__background\"><\/div><div class=\"wp-block-getwid-section__foreground\"><\/div><\/div><div class=\"wp-block-getwid-section__content\"><div class=\"wp-block-getwid-section__inner-content\">\n<div class=\"wp-block-image is-style-default\"><figure class=\"alignleft size-large is-resized\"><a href=\"https:\/\/ritme.com\/it\/software\/chemdraw-chemoffice\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/LOGO_ChemDraw18.png\" alt=\"\" class=\"wp-image-11890\" width=\"270\" height=\"42\"\/><\/a><\/figure><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:10px\" aria-hidden=\"true\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/chemoffice-plus-cloud-1024x466.png\" alt=\"\" class=\"wp-image-12031\" width=\"285\" height=\"129\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/chemoffice-plus-cloud-1024x466.png 1024w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/chemoffice-plus-cloud-500x227.png 500w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/chemoffice-plus-cloud-768x349.png 768w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/chemoffice-plus-cloud.png 1258w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-getwid-section getwid-margin-top-none getwid-margin-bottom-none\"><div class=\"wp-block-getwid-section__wrapper getwid-padding-bottom-medium getwid-padding-right-none getwid-margin-left-none getwid-margin-right-none\" style=\"padding-left:5px\"><div class=\"wp-block-getwid-section__inner-wrapper\"><div class=\"wp-block-getwid-section__background-holder\"><div class=\"wp-block-getwid-section__background\"><\/div><div class=\"wp-block-getwid-section__foreground\"><\/div><\/div><div class=\"wp-block-getwid-section__content\"><div class=\"wp-block-getwid-section__inner-content\">\n<p class=\"has-text-align-left read-more wp-block-paragraph\"><a href=\"https:\/\/ritme.com\/it\/software\/chemdraw-chemoffice\/\">scoprire Chemdraw<\/a> <\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-186e8ba3\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<p class=\"wp-block-paragraph\">ChemDraw si \u00e8 affermato da tempo come il software di riferimento per il disegno di strutture molecolari. Per offrire ad ogni utente lo strumento adatto alle sue necessit\u00e0, il software esiste ora in tre versioni: ChemDraw Prime, ChemDraw Professional e ChemOffice+ Cloud. Queste versioni soddisfano le esigenze di tutti i ricercatori, studenti e insegnanti coinvolti nella chimica e nei campi correlati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ChemDraw Professional per Mac e ChemOffice+ Cloud ora includono un quaderno di laboratorio elettronico accessibile via cloud, permettendo una collaborazione facile e senza restrizioni.<\/p>\n<\/div><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-045470b3 cta-type-1\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-getwid-anchor\" title=\"Read CTA\"><\/div>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><em>Per aiutarvi a rispondere a questi problemi con soluzioni tangibili, \u00e8 essenziale esaminare il vostro business, la vostra struttura e il posto che la gestione e l&#8217;organizzazione della conoscenza, ora chiamata Information Intelligence, pu\u00f2 prendere.<\/em><\/h3>\n\n\n\n<div class=\"wp-block-buttons aligncenter is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-icon icon-eye\"><a class=\"wp-block-button__link\" href=\"https:\/\/ritme.com\/it\/soluzioni\/\">leggere di pi\u00f9<\/a><\/div>\n<\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-color uagb-block-cac29e3a cta-type-1\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\"><div class=\"testimonial-wrapper teaser \"><div class=\"testimonial\">\n\t<div class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"350\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/09\/img_logo-BRRC-2.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/09\/img_logo-BRRC-2.png 705w, https:\/\/ritme.com\/wp-content\/uploads\/2021\/09\/img_logo-BRRC-2-500x248.png 500w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/div>\n\t<div class=\"content\">\n\t\t<div class=\"text\">\n\t\t\t<div class=\"text-inner\">\n\t\t\t\tI nostri ricercatori non lavorano da soli, lavorano in team su progetti comuni. L&#8217;aspetto collaborativo di citavi \u00e8 chiaramente una risorsa. (&#8230;). <strong>Citavi porta anche un grande rigore<\/strong>, ci sono molti meno errori nelle nostre bibliografie finali e quindi molto meno lavoro di correzione manuale. <strong>Citavi ci garantisce bibliografie conformi agli standard e alle esigenze editoriali. In sintesi, citavi ci ha portato una migliore collaborazione in tutto il nostro processo di ricerca, un risultato migliore in termini di qualit\u00e0, un enorme risparmio di tempo<\/strong> e una facilit\u00e0 di condivisione delle conoscenze.\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"author-wrapper\">\n\t\t\t<div class=\"name\">Jesica De Salvador<\/div>\n\t\t\t\t\t\t\t<div class=\"function\">Documentalista &#8211; Centro di Ricerca Stradale<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"software\">Citavi<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:40px\" aria-hidden=\"true\"><\/div>\n\n\n\n<div class=\"wp-block-buttons aligncenter is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-icon icon-eye\"><a class=\"wp-block-button__link\" href=\"https:\/\/ritme.com\/it\/citavi-case-study\/\">LEGGERE DI PI\u00d9<\/a><\/div>\n<\/div>\n<\/div><\/section>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-d53485d5\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\"><div class=\"sidebar-submenu wp-block-create-block-sidebar siblings-style-cards hide-current-page\"><div class=\"backend-only\">Internal links are generated on the front page only.<\/div><ul class=\"siblings\"><li class=\"page_item page-item-15015\"><a href=\"https:\/\/ritme.com\/it\/soluzioni\/gestione-e-condivisione-dei-dati-2\/\">Gestione e condivisione dei dati<\/a><\/li>\n<li class=\"page_item page-item-2820\"><a href=\"https:\/\/ritme.com\/it\/soluzioni\/analyse-et-traitement-des-donnees\/\">Analyse et traitement des donn\u00e9es<\/a><\/li>\n<li class=\"page_item page-item-2843\"><a href=\"https:\/\/ritme.com\/it\/soluzioni\/valorizzare-i-dati\/\">Valorizzare i dati<\/a><\/li>\n<li class=\"page_item page-item-7394\"><a href=\"https:\/\/ritme.com\/it\/soluzioni\/qualita-e-sicurezza\/\">Qualit\u00e0 e sicurezza<\/a><\/li>\n<li class=\"page_item page-item-2851\"><a href=\"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/\">Pubblicazione e comunicazione<\/a><\/li>\n<\/ul><\/div><\/div><\/div>\n<\/div><\/section>\n\n\n\n<div class=\"wp-block-getwid-advanced-spacer\" style=\"height:70px\" aria-hidden=\"true\"><\/div>\n\n\n<section id=\"formation-software-promo-block_604f93d23f9f2\" class=\"formation-software-promo not-editable\">\n\t<div class=\"row\">\n\t\t<div class=\"col col-form custom-shadow\">\n\t\t\t<div class=\"card\">\n\t\t\t\t<p><strong>Sta cercando informazioni su un corso di formazione?<\/strong><\/p>\n<p><strong>Vuole organizzare una sessione di formazione personalizzata?<\/strong><\/p>\n<p><strong>Contatta il nostro team pedagogico!<\/strong><\/p>\n\t\t\t\t<div class=\"form-wrapper\">\n\t\t\t\t\t<noscript class=\"ninja-forms-noscript-message\">\n\tAvviso: JavaScript \u00e8 obbligatorio per questo contenuto.<\/noscript>\n<div id=\"nf-form-3-cont\" class=\"nf-form-cont simple-form\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-3\" aria-describedby=\"nf-form-errors-3\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- That data is being printed as a workaround to page builders reordering the order of the scripts loaded-->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='3';form.settings={\"objectType\":\"Form Setting\",\"editActive\":true,\"title\":\"Formulaire simple\",\"show_title\":0,\"allow_public_link\":0,\"embed_form\":\"\",\"clear_complete\":1,\"hide_complete\":1,\"default_label_pos\":\"above\",\"wrapper_class\":\"simple-form\",\"element_class\":\"\",\"key\":\"\",\"add_submit\":0,\"currency\":\"\",\"repeatable_fieldsets\":\"\",\"unique_field_error\":\"\",\"logged_in\":false,\"not_logged_in_msg\":\"\",\"sub_limit_msg\":\"\",\"calculations\":[],\"formContentData\":[\"last_name\",\"first_name\",\"email\",\"message\",\"rgpd_1623255641451\",\"envoyer_ma_demande_1614853054227\",\"source\",\"crm_subject\",\"visitor_country\",\"visitor_language\"],\"changeEmailErrorMsg\":\"Immetti un indirizzo email valido.\",\"changeDateErrorMsg\":\"Please enter a valid date!\",\"confirmFieldErrorMsg\":\"Questi campi devono corrispondere.\",\"fieldNumberNumMinError\":\"Errore numero min\",\"fieldNumberNumMaxError\":\"Errore numero max\",\"fieldNumberIncrementBy\":\"Incrementa di \",\"formErrorsCorrectErrors\":\"Correggi gli errori prima di inviare il form.\",\"validateRequiredField\":\"Campo obbligatorio.\",\"honeypotHoneypotError\":\"Errore Honeypot\",\"fieldsMarkedRequired\":\"I campi contrassegnati con <span class=\\\"ninja-forms-req-symbol\\\">*<\\\/span> sono obbligatori.\",\"drawerDisabled\":false,\"conditions\":[],\"ninjaForms\":\"Ninja Forms\",\"fieldTextareaRTEInsertLink\":\"Inserisci link\",\"fieldTextareaRTEInsertMedia\":\"Inserisci media\",\"fieldTextareaRTESelectAFile\":\"Seleziona un file\",\"tableInsertRowAbove\":\"Insert Row Above\",\"tableInsertRowBelow\":\"Insert Row Below\",\"tableInsertColumnLeft\":\"Insert Column Left\",\"tableInsertColumnRight\":\"Insert Column Right\",\"tableDeleteRow\":\"Delete Row\",\"tableDeleteColumn\":\"Delete Column\",\"tableDeleteTable\":\"Delete Table\",\"tableLegacyNotice\":\"This content has tables in the old editor format. Custom styles are preserved until converted. Editing will update to the new format.\",\"tableLegacyConvert\":\"Convert Now\",\"tableInsertTable\":\"Insert Table\",\"dismiss\":\"Chiudi\",\"insertLink\":\"Inserisci link\",\"formHoneypot\":\"Se sei un essere umano e vedi questo campo, lascialo vuoto.\",\"fileUploadOldCodeFileUploadInProgress\":\"Caricamento file in corso.\",\"fileUploadOldCodeFileUpload\":\"CARICAMENTO FILE\",\"currencySymbol\":\"&#36;\",\"thousands_sep\":\".\",\"decimal_point\":\",\",\"siteLocale\":\"it_IT\",\"dateFormat\":\"m\\\/d\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"di\",\"previousMonth\":\"Previous Month\",\"nextMonth\":\"Next Month\",\"months\":[\"January\",\"February\",\"March\",\"April\",\"May\",\"June\",\"July\",\"August\",\"September\",\"October\",\"November\",\"December\"],\"monthsShort\":[\"Jan\",\"Feb\",\"Mar\",\"Apr\",\"May\",\"Jun\",\"Jul\",\"Aug\",\"Sep\",\"Oct\",\"Nov\",\"Dec\"],\"weekdays\":[\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\"],\"weekdaysShort\":[\"Sun\",\"Mon\",\"Tue\",\"Wed\",\"Thu\",\"Fri\",\"Sat\"],\"weekdaysMin\":[\"Su\",\"Mo\",\"Tu\",\"We\",\"Th\",\"Fr\",\"Sa\"],\"recaptchaConsentMissing\":\"reCaptcha validation couldn&#039;t load.\",\"recaptchaMissingCookie\":\"reCaptcha v3 validation couldn&#039;t load the cookie needed to submit the form.\",\"recaptchaConsentEvent\":\"Accept reCaptcha cookies before sending the form.\",\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":1,\"idAttribute\":\"id\",\"type\":\"lastname\",\"label\":\"Nome\",\"key\":\"last_name\",\"label_pos\":\"hidden\",\"required\":1,\"default\":\"\",\"placeholder\":\"Nome\",\"container_class\":\"one-half first\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"last_name\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":false,\"manual_key\":true,\"id\":12,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"lastname\",\"element_templates\":[\"lastname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":2,\"idAttribute\":\"id\",\"label\":\"Nome e cognome\",\"type\":\"firstname\",\"key\":\"first_name\",\"label_pos\":\"hidden\",\"required\":0,\"default\":\"\",\"placeholder\":\"Nome e cognome\",\"container_class\":\"one-half second\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"first_name\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":false,\"manual_key\":true,\"id\":58,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"firstname\",\"element_templates\":[\"firstname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":3,\"idAttribute\":\"id\",\"type\":\"email\",\"label\":\"E-mail\",\"key\":\"email\",\"label_pos\":\"hidden\",\"required\":1,\"default\":\"\",\"placeholder\":\"E-mail\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"email\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":false,\"manual_key\":true,\"id\":13,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"email\",\"element_templates\":[\"email\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":4,\"idAttribute\":\"id\",\"type\":\"textarea\",\"label\":\"Message\",\"key\":\"message\",\"label_pos\":\"hidden\",\"required\":1,\"default\":\"\",\"placeholder\":\"Inserisci qui la tua domanda\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Caract\\u00e8res restants\",\"manual_key\":true,\"admin_label\":\"\",\"help_text\":\"\",\"textarea_rte\":\"\",\"disable_rte_mobile\":\"\",\"textarea_media\":\"\",\"value\":\"\",\"drawerDisabled\":false,\"id\":14,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textarea\",\"element_templates\":[\"textarea\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":5,\"idAttribute\":\"id\",\"type\":\"html\",\"label\":\"RGPD\",\"default\":\"<p>Ritme attribuisce grande importanza alla riservatezza dei vostri dati. I dati raccolti in questo modulo sono trattati da Ritme al fine di gestire la vostra richiesta di contatto, la vostra registrazione sul sito e per inviarti newsletter (novit\\u00e0, prodotti, eventi). Per saperne di pi\\u00f9 sulla gestione dei suoi dati personali e per esercitare i suoi diritti, la invitiamo a leggere la nostra <a href=\\\"https:\\\/\\\/ritme.alwaysdata.net\\\/it\\\/privacy-dei-dati\\\/\\\">Politica sulla privacy<\\\/a><br><\\\/p>\",\"container_class\":\"small-text\",\"element_class\":\"\",\"key\":\"rgpd_1623255641451\",\"drawerDisabled\":false,\"id\":93,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"<p>Ritme attribuisce grande importanza alla riservatezza dei vostri dati. I dati raccolti in questo modulo sono trattati da Ritme al fine di gestire la vostra richiesta di contatto, la vostra registrazione sul sito e per inviarti newsletter (novit\\u00e0, prodotti, eventi). Per saperne di pi\\u00f9 sulla gestione dei suoi dati personali e per esercitare i suoi diritti, la invitiamo a leggere la nostra <a href=\\\"https:\\\/\\\/ritme.alwaysdata.net\\\/it\\\/privacy-dei-dati\\\/\\\">Politica sulla privacy<\\\/a><br><\\\/p>\",\"label_pos\":\"above\",\"parentType\":\"html\",\"element_templates\":[\"html\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":6,\"idAttribute\":\"id\",\"type\":\"submit\",\"label\":\"Inviare la mia richiesta\",\"processing_label\":\"In corso\",\"container_class\":\"text-center\",\"element_class\":\"is-next\",\"key\":\"envoyer_ma_demande_1614853054227\",\"drawerDisabled\":false,\"id\":15,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"above\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":8,\"idAttribute\":\"id\",\"type\":\"hidden\",\"label\":\"Source\",\"key\":\"source\",\"default\":\"\",\"admin_label\":\"\",\"manual_key\":true,\"drawerDisabled\":false,\"id\":60,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"Pubblicazione e comunicazione\",\"label_pos\":\"above\",\"parentType\":\"hidden\",\"element_templates\":[\"hidden\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":9,\"idAttribute\":\"id\",\"type\":\"hidden\",\"label\":\"CRM Subject\",\"key\":\"crm_subject\",\"default\":\"Demande d'information\",\"admin_label\":\"\",\"drawerDisabled\":false,\"manual_key\":true,\"id\":68,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"Demande d'information\",\"label_pos\":\"above\",\"parentType\":\"hidden\",\"element_templates\":[\"hidden\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":10,\"idAttribute\":\"id\",\"type\":\"hidden\",\"label\":\"Visitor Country\",\"key\":\"visitor_country\",\"default\":\"\",\"admin_label\":\"\",\"manual_key\":true,\"drawerDisabled\":false,\"id\":88,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"fr\",\"label_pos\":\"above\",\"parentType\":\"hidden\",\"element_templates\":[\"hidden\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":11,\"idAttribute\":\"id\",\"type\":\"hidden\",\"label\":\"Visitor Language\",\"key\":\"visitor_language\",\"default\":\"\",\"admin_label\":\"\",\"manual_key\":true,\"drawerDisabled\":false,\"id\":89,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"it\",\"label_pos\":\"above\",\"parentType\":\"hidden\",\"element_templates\":[\"hidden\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n        \t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col col-promo\">\n\t\t\t\t\t\t\t<div class=\"software-promo\">\n\t\t\t\t\t<a class=\"image\" href=\"https:\/\/ritme.com\/it\/software\/nvivo\/\"><img decoding=\"async\" src=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/03\/img_NVivo_Mise-en-avant-1.png\"\/><\/a>\n\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t<a class=\"title\" href=\"https:\/\/ritme.com\/it\/software\/nvivo\/\">NVivo<\/a>\n\t\t\t\t\t\t<div class=\"description\">NVivo \u00e8 il software di analisi dei dati qualitativi progettato per fornirti uno spazio di lavoro dove puoi organizzare, visualizzare e analizzare i vostri dati qualitativi e non strutturati. \r\nNVivo gestisce diverse fonti di dati e formati come interviste, risultati di sondaggi, immagini, interviste audio o video, articoli di giornale, contenuti di pagine web e social network. <\/div>\n\t\t\t\t\t\t<div class=\"more-link link-text text-right\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/ritme.com\/it\/software\/nvivo\/\">Leggere di pi\u00f9<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Spesso alla fine del lavoro di ricerca, la pubblicazione e la comunicazione sono la vetrina delle tue capacit\u00e0. Per coprire tutte le tappe, vi mettiamo a disposizione soluzioni per la gestione delle vostre risorse documentarie, l&#8217;orologio scientifico, la progettazione molecolare o i supporti di comunicazione: tante soluzioni da scoprire nella nostra offerta.<\/p>\n","protected":false},"author":1,"featured_media":11556,"parent":916,"menu_order":238,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-2851","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pubblicazione e comunicazione - RITME<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pubblicazione e comunicazione - RITME\" \/>\n<meta property=\"og:description\" content=\"Spesso alla fine del lavoro di ricerca, la pubblicazione e la comunicazione sono la vetrina delle tue capacit\u00e0. Per coprire tutte le tappe, vi mettiamo a disposizione soluzioni per la gestione delle vostre risorse documentarie, l&#039;orologio scientifico, la progettazione molecolare o i supporti di comunicazione: tante soluzioni da scoprire nella nostra offerta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/\" \/>\n<meta property=\"og:site_name\" content=\"RITME\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-28T15:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1358\" \/>\n\t<meta property=\"og:image:height\" content=\"1199\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/pubblicazione-e-comunicazione\\\/\",\"url\":\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/pubblicazione-e-comunicazione\\\/\",\"name\":\"Pubblicazione e comunicazione - RITME\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/pubblicazione-e-comunicazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/pubblicazione-e-comunicazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Publication-et-communication_1-8.png\",\"datePublished\":\"2021-03-18T14:36:42+00:00\",\"dateModified\":\"2021-09-28T15:50:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/pubblicazione-e-comunicazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/pubblicazione-e-comunicazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/pubblicazione-e-comunicazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Publication-et-communication_1-8.png\",\"contentUrl\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Publication-et-communication_1-8.png\",\"width\":1358,\"height\":1199},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/pubblicazione-e-comunicazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ritme.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluzioni\",\"item\":\"https:\\\/\\\/ritme.com\\\/it\\\/soluzioni\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pubblicazione e comunicazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ritme.com\\\/it\\\/\",\"name\":\"RITME\",\"description\":\"Il partner strategico dei team di ricerca\",\"publisher\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ritme.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#organization\",\"name\":\"RITME\",\"url\":\"https:\\\/\\\/ritme.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Logo-Yoast.png\",\"contentUrl\":\"https:\\\/\\\/ritme.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Logo-Yoast.png\",\"width\":696,\"height\":696,\"caption\":\"RITME\"},\"image\":{\"@id\":\"https:\\\/\\\/ritme.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ritme-scientific-solutions\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ritme6705\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pubblicazione e comunicazione - RITME","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/","og_locale":"it_IT","og_type":"article","og_title":"Pubblicazione e comunicazione - RITME","og_description":"Spesso alla fine del lavoro di ricerca, la pubblicazione e la comunicazione sono la vetrina delle tue capacit\u00e0. Per coprire tutte le tappe, vi mettiamo a disposizione soluzioni per la gestione delle vostre risorse documentarie, l'orologio scientifico, la progettazione molecolare o i supporti di comunicazione: tante soluzioni da scoprire nella nostra offerta.","og_url":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/","og_site_name":"RITME","article_modified_time":"2021-09-28T15:50:32+00:00","og_image":[{"width":1358,"height":1199,"url":"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/","url":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/","name":"Pubblicazione e comunicazione - RITME","isPartOf":{"@id":"https:\/\/ritme.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/#primaryimage"},"image":{"@id":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/#primaryimage"},"thumbnailUrl":"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8.png","datePublished":"2021-03-18T14:36:42+00:00","dateModified":"2021-09-28T15:50:32+00:00","breadcrumb":{"@id":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/#primaryimage","url":"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8.png","contentUrl":"https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8.png","width":1358,"height":1199},{"@type":"BreadcrumbList","@id":"https:\/\/ritme.com\/it\/soluzioni\/pubblicazione-e-comunicazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ritme.com\/it\/"},{"@type":"ListItem","position":2,"name":"Soluzioni","item":"https:\/\/ritme.com\/it\/soluzioni\/"},{"@type":"ListItem","position":3,"name":"Pubblicazione e comunicazione"}]},{"@type":"WebSite","@id":"https:\/\/ritme.com\/it\/#website","url":"https:\/\/ritme.com\/it\/","name":"RITME","description":"Il partner strategico dei team di ricerca","publisher":{"@id":"https:\/\/ritme.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ritme.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ritme.com\/it\/#organization","name":"RITME","url":"https:\/\/ritme.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ritme.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ritme.com\/wp-content\/uploads\/2026\/05\/Logo-Yoast.png","contentUrl":"https:\/\/ritme.com\/wp-content\/uploads\/2026\/05\/Logo-Yoast.png","width":696,"height":696,"caption":"RITME"},"image":{"@id":"https:\/\/ritme.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/ritme-scientific-solutions\/","https:\/\/www.youtube.com\/@ritme6705"]}]}},"uagb_featured_image_src":{"full":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8.png",1358,1199,false],"thumbnail":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8-300x300.png",300,300,true],"medium":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8-500x441.png",500,441,true],"medium_large":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8-768x678.png",768,678,true],"large":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8-1024x904.png",1024,904,true],"1536x1536":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8.png",1358,1199,false],"2048x2048":["https:\/\/ritme.com\/wp-content\/uploads\/2021\/06\/Publication-et-communication_1-8.png",1358,1199,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/ritme.com\/it\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Spesso alla fine del lavoro di ricerca, la pubblicazione e la comunicazione sono la vetrina delle tue capacit\u00e0. Per coprire tutte le tappe, vi mettiamo a disposizione soluzioni per la gestione delle vostre risorse documentarie, l'orologio scientifico, la progettazione molecolare o i supporti di comunicazione: tante soluzioni da scoprire nella nostra offerta.","_links":{"self":[{"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/pages\/2851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/comments?post=2851"}],"version-history":[{"count":2,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/pages\/2851\/revisions"}],"predecessor-version":[{"id":19527,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/pages\/2851\/revisions\/19527"}],"up":[{"embeddable":true,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/pages\/916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/media\/11556"}],"wp:attachment":[{"href":"https:\/\/ritme.com\/it\/wp-json\/wp\/v2\/media?parent=2851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}